{"id":8400,"date":"2014-02-14T06:58:12","date_gmt":"2014-02-14T06:58:12","guid":{"rendered":"http:\/\/lacittafutura.net\/adrianozanon\/?p=8400"},"modified":"2014-02-15T11:47:06","modified_gmt":"2014-02-15T11:47:06","slug":"la-leggenda-di-marco-pantani","status":"publish","type":"post","link":"https:\/\/lacittafutura.net\/adrianozanon\/2014\/02\/14\/la-leggenda-di-marco-pantani\/","title":{"rendered":"Marco Pantani, la leggenda finale"},"content":{"rendered":"<p><strong>Dieci anni fa moriva <a href=\"https:\/\/it.wikipedia.org\/wiki\/Marco_Pantani\">Marco Pantani<\/a><\/strong> (Cesena, 13 gennaio 1970 &#8211; Rimini, 14 febbraio 2004), l&#8217;ultima leggenda del\u00a0ciclismo su strada, probabilmente quella finale.<\/p>\n<p><a href=\"http:\/\/lacittafutura.net\/adrianozanon\/files\/2014\/02\/20140211_lance_armstrong_e_marco_pantani_sul_mont_ventoux_2000.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Lance Armstrong e Marco Pantani sul Mont Ventoux (2000)\" class=\"aligncenter size-full wp-image-8407\" width=\"834\" height=\"660\" src=\"http:\/\/lacittafutura.net\/adrianozanon\/files\/2014\/02\/20140211_lance_armstrong_e_marco_pantani_sul_mont_ventoux_2000.jpg\" alt=\"\" srcset=\"https:\/\/lacittafutura.net\/adrianozanon\/files\/2014\/02\/20140211_lance_armstrong_e_marco_pantani_sul_mont_ventoux_2000.jpg 834w, https:\/\/lacittafutura.net\/adrianozanon\/files\/2014\/02\/20140211_lance_armstrong_e_marco_pantani_sul_mont_ventoux_2000-300x237.jpg 300w\" sizes=\"auto, (max-width: 834px) 100vw, 834px\" \/><\/a><\/p>\n<p>Si sono scritte e pubblicate tante cose, ma su Pantani il migliore resta sempre <a href=\"http:\/\/www.repubblica.it\/sport\/ciclismo\/2014\/02\/11\/news\/pantani_un_uomo_sempre_solo_quando_vinceva_e_quando_sbandava-78251542\/?ref=HRERO-1\">Gianni Mura<\/a> che non pretende di saperne pi\u00f9 di altri, ma solo di continuare ad avere dei dubbi. Estraggo questo:<\/p>\n<h5 style=\"padding-left: 30px;\">Come quella di Pantani. Che ha due grandi punti interrogativi su due stanze d\u2019albergo. Una \u00e8 quella di Madonna di Campiglio, 5 giugno 1999, l\u2019inizio della fine. Come mai, trattandosi di una visita annunciata, non a sorpresa, il sangue di Pantani presentava un ematocrito a 52? E cosa accadde veramente nella stanza D5 del residence Le Rose, a Rimini, la fine della fine? Un libro di Philippe Brunel dell\u2019Equipe ha documentato quante smagliature e lacune ci fossero nell\u2019inchiesta. I dubbi restano e quel residence non c\u2019\u00e8 pi\u00f9, \u00e8 stato demolito in tempi brevi, sorprendenti per la burocrazia nostrana.<\/h5>\n<h5 style=\"padding-left: 30px;\">I dubbi non restano in chi parla di Pantani solo come di un drogato, in bici e gi\u00f9 dalla bici, o solo come di un angelo innocente tirato gi\u00f9 dal cielo. Rivivere quegli anni, tra la fine degli \u201980 e poco oltre il 2000, \u00e8 come seguire le piste dell\u2019Epo. Pantani ne ha fatto uso? S\u00ec, come tutti. In che misura? Pastonesi cita livelli alquanto alti. Avrebbe vinto ugualmente? S\u00ec, a parit\u00e0 di carburante. Ma, a Pantani morto, \u00e8 saltato fuori che su qualcuno (Armstrong) l\u2019Uci teneva aperto un larghissimo ombrello.<\/h5>\n<h5 style=\"padding-left: 30px;\">Per onest\u00e0, come Pastonesi ha scritto che Pantani non era uno dei suoi, devo scrivere che Pantani \u00e8 stato uno dei miei. Perch\u00e9, come i vecchi ciclisti, in corsa faceva di testa sua, non usava il cardiofrequenzimetro e quando s\u2019allenava dalle sue parti beveva alle fontane e mangiava pane e pecorino. Perch\u00e9, pi\u00f9 ancora delle vittorie, ricordo l\u2019attesa delle vittorie, o comunque dell\u2019attacco in salita. E l\u2019entusiasmo della gente, come un ascensore sonoro fra tornante e tornante. E l\u2019Italia sulla canna di quella bicicletta, e i francesi che s\u2019incazzavano, ma neanche tanto. Perch\u00e9 gli piaceva ascoltare Charlie Parker.<\/h5>\n<h5 style=\"padding-left: 30px;\">(Gianni Mura, &#8220;Pantani, un uomo sempre solo, quando vinceva e quando sbandava&#8221;, <em>la Repubblica<\/em>, 11 febbraio 2014)<\/h5>\n<h5 style=\"padding-left: 30px;\">Dove i riferimenti sono:<br \/>\nPastonesi Marco, <em>Pantani era un dio<\/em>, 66th and 2nd, Roma 2014;<br \/>\nBrunel Philippe, <em>Gli ultimi giorni di Marco Pantani<\/em>, Bur, Milano 2011.<\/h5>\n<p>Per una sintesi anche sportiva rimando (immodestamente) anche alla <a href=\"http:\/\/lacittafutura.net\/blog\/2009\/08\/01\/lettere-a-fausto-marco-pantani\/\">Lettera a Fausto <\/a>del 1\u00b0 agosto 2009, su questo stesso sito. Dove (modestamente) Marco scriveva gi\u00e0 a Fausto: &#8220;A Parigi mi sentivo un dio. Ero bello come un dio. Ero un dio.&#8221; <\/p>\n<p>Infine, commemorare Pantani con la foto di lui ed\u00a0Armstrong\u00a0sul Mont Ventoux nel 2000 \u00e8 volutamente provocatorio.\u00a0Con Armstrong &#8211; che \u00e8 il simbolo dell&#8217;organizzazione del business sportivo nel mondo attuale &#8211; il ciclismo storico \u00e8 finito definitivamente, ci resteranno solo alcune leggende, come quella di Marco Pantani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieci anni fa moriva Marco Pantani (Cesena, 13 gennaio 1970 &#8211; Rimini, 14 febbraio 2004), l&#8217;ultima leggenda del\u00a0ciclismo su strada, probabilmente quella finale. Si sono scritte e pubblicate tante cose, ma su Pantani il migliore resta sempre Gianni Mura che &hellip; <a href=\"https:\/\/lacittafutura.net\/adrianozanon\/2014\/02\/14\/la-leggenda-di-marco-pantani\/\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,131],"tags":[121,35],"class_list":["post-8400","post","type-post","status-publish","format-standard","hentry","category-cultura","category-societa","tag-ciclismo","tag-mem"],"_links":{"self":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/comments?post=8400"}],"version-history":[{"count":23,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8400\/revisions"}],"predecessor-version":[{"id":8415,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8400\/revisions\/8415"}],"wp:attachment":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/media?parent=8400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/categories?post=8400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/tags?post=8400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}