{"id":8291,"date":"2014-02-07T13:31:45","date_gmt":"2014-02-07T13:31:45","guid":{"rendered":"http:\/\/lacittafutura.net\/adrianozanon\/?p=8291"},"modified":"2014-02-20T20:08:34","modified_gmt":"2014-02-20T20:08:34","slug":"tsipras-un-greco-come-leader","status":"publish","type":"post","link":"https:\/\/lacittafutura.net\/adrianozanon\/2014\/02\/07\/tsipras-un-greco-come-leader\/","title":{"rendered":"Tsipras, un greco come leader europeo"},"content":{"rendered":"<p>Oggi <em>la Repubblica <\/em>(p.11) pubblica un&#8217;intervista con <a href=\"https:\/\/el.wikipedia.org\/wiki\/%CE%91%CE%BB%CE%AD%CE%BE%CE%B7%CF%82_%CE%A4%CF%83%CE%AF%CF%80%CF%81%CE%B1%CF%82\">Alexis Tsipras <\/a>raccolta durante il suo tour italiano di questi giorni. Il mio link \u00e8 dal sito di ALBA.<br \/>\n___________________<\/p>\n<h5><a href=\"http:\/\/www.albasoggettopoliticonuovo.it\/2014\/02\/tsipras-e-la-sfida-di-sinistra-alla-ue-la-linea-merkel-porta-solo-poverta-per-batterla-cerco-alleati-in-italia-da-repubblica\/\">L\u2019intervista<\/a><br \/>\n<strong> Tsipras e la sfida di sinistra alla Ue<br \/>\n\u201cLa linea Merkel porta solo povert\u00e0 per batterla cerco alleati in Italia\u201d<\/strong><br \/>\n<em> Il leader greco di Syriza oggi a Roma per lanciare la sua lista<\/em><\/h5>\n<h5>ETTORE LIVINI<br \/>\nMATTEO PUCCIARELLI<\/h5>\n<h5>MILANO \u2014 \u00c8 la stella della sinistra radicale europea. Neanche 40 anni, Alexis Tsipras \u00e8 riuscito a trasformare la litigiosa e minoritaria area greca neo-post comunista in un unico soggetto (Syriza) diventato \u2014 secondo i sondaggi \u2014 il primo partito. \u00c8 all\u2019opposizione del governo di larghe intese, e pi\u00f9 passano mesi e pi\u00f9 i suoi consensi aumentano. La prossima sfida \u00e8 per\u00f2 continentale: per questo la sinistra europea (Gue) lo ha candidato alla presidenza della Commissione. Un po\u2019 Davide contro Golia: la cenerentola greca contro la Germania. In Italia un gruppo di intellettuali (tra cui Barbara Spinelli e Luciano Gallino) sta varando una lista a suo sostegno in vista delle europee, con l\u2019appoggio di Sel e Rifondazione. Oggi Tsipras sar\u00e0 a Roma: debutto al Teatro Valle. Un luogo simbolico. \u201cCom\u2019\u00e8 triste la prudenza\u201d, recita un gigantesco striscione nello spazio occupato nel centro della Capitale: un motto in cui si ritrova molto.<\/h5>\n<h5 style=\"padding-left: 30px;\"><strong><em>Der Spiegel<\/em> l\u2019ha definita \u201cil nemico numero uno dell\u2019Europa\u201d. Si sente davvero una minaccia?<\/strong><br \/>\n\u00abCerto, sono il rivale dell\u2019Europa dei mercati e delle disuguaglianze sociali. Ma siamo anche l\u2019unica speranza per quella solidale, dei popoli, della democrazia, della dignit\u00e0\u00bb.<\/h5>\n<h5 style=\"padding-left: 30px;\"><strong>Tra i \u201ccattivi\u201d ci mette anche i socialdemocratici?<\/strong><br \/>\n\u00abLe politiche neoliberiste stanno disgregando la Ue. E finora conservatori e riformisti sono andati entrambi in questa direzione \u00bb.<\/h5>\n<h5><strong>Angela Merkel e il candidato presidente dei socialdemocratici Martin Schulz sono la stessa cosa?<\/strong><br \/>\n\u00abA me Schulz sta simpatico. Ma da venti anni la socialdemocrazia si \u00e8 tagliata fuori dalla sua tradizionale base politica e sociale. Spero nella loro svolta a sinistra. Non puoi sostenere una prospettiva diversa da quella dell\u2019austerit\u00e0 e poi andare a braccetto con la signora Merkel\u00bb.<\/h5>\n<h5><strong>Ovvero?<\/strong><br \/>\n\u00abQuanto fatto dal 2008 ad oggi verr\u00e0 insegnato nelle facolt\u00e0 di Economia, ma come esempio da evitare. La crisi \u00e8 figlia delle asimmetrie dell\u2019unione monetaria. E l\u2019<em>establishment<\/em> politico europeo sorretto da popolari e socialisti con l\u2019austerit\u00e0 ha peggiorato la situazione. Per cosa, poi? Per salvare le banche che avevano titoli di Stato dei paesi altamente indebitati. J\u00fcrgen Habermas ha dettoche la gestione della crisi \u201cnon solo non affronta le cause che l\u2019hanno provocata, ma nasconde anche il pericolo di andare verso un\u2019Europa tedesca\u201d. La vedo cos\u00ec\u00bb.<\/h5>\n<h5 style=\"padding-left: 30px;\"><strong>Cosa si dovrebbe fare allora?<\/strong><br \/>\n\u00abUna conferenza europea per il debito, sul modello di quella del \u201853 che cancell\u00f2 gran parte del debito della Germania postbellica, dandole la spinta necessaria per il miracolo economico. La Bce dovrebbe funzionare come una vera banca centrale, simile a quella americana, che presti agli Stati e non solo alle banche. Poi legiferare affinch\u00e9 si separino attivit\u00e0 commerciali e quelle di investimento delle banche. \u00c8 urgente varare un <em>New Deal<\/em> europeo, un piano di investimenti pubblici per lo sviluppo. Gli attuali vertici della Ue hanno utilizzato la crisi per imporre il modello del capitalismo neoliberista, scatenando un attacco senza precedenti al mondo del lavoro\u00bb.<\/h5>\n<h5><strong>Wolfgang Sch\u00e4uble spiega che la cura greca sta funzionando. Le previsioni del Pil greco per il 2014 sono positive. C\u2019\u00e8 stato un avanzo primario della spesa.<\/strong><br \/>\n\u00abA quale prezzo? Una disastro mai visto: disoccupazione al 30 per cento, il 35 per cento della popolazione a ridosso della povert\u00e0. Chiusura di ospedali, fusioni di scuole. Ad Atene giri per strada e trovi gente ben vestita che rovista nella spazzatura. Tutto questo \u00e8 insostenibile. Quanto al Pil, lo dice la<em> troika<\/em>:l\u2019Ocse rileva invece che la recessione continuer\u00e0\u00bb.<\/h5>\n<h5><strong>I movimenti populisti crescono ovunque. Da voi i fascisti di Alba Dorata sono il terzo partito, nonostante l\u2019arresto del suo leader e l\u2019omicidio di un vostro militante. Come si ferma la loro avanzata?<\/strong><br \/>\n\u00abSono il prodotto politico del liberismo. Alba Dorata \u00e8 passata dallo 0,3 al 7 per cento proprio negli anni dell\u2019austerit\u00e0. Fomentano rabbia e disperazione, ma verso i pi\u00f9 deboli, gli immigrati. Sono falsi nemici del sistema: non se la prendono con i forti, ma con i debolissimi\u00bb.<\/h5>\n<h5 style=\"padding-left: 30px;\"><strong>Cosa pensa della lista italiana a suo sostegno?<\/strong><br \/>\n\u00abCredo vada costruita dal basso, con i movimenti, gli intellettuali, la societ\u00e0 civile. Come sta avvenendo. Cittadini che si auto-organizzano insieme alle associazioni e alle altre forze che vogliono partecipare. Mettendo le differenze da parte: fare un passo indietro tutti per farne molti in avanti, insieme\u00bb.<\/h5>\n<h5 style=\"padding-left: 30px;\"><strong>Conosce Matteo Renzi e Beppe Grillo?<\/strong><br \/>\n\u00abSo che a Renzi sembrano andar bene gli attuali equilibri europei, mentre a Grillo sembra importare poco e basta: risposte che trovo sbagliate e inadeguate. Ma non esiter\u00f2 a chiedere loro una mano se da primo ministro greco mi metter\u00f2 a capo di un duro processo di rinegoziazione nella Ue per conto di tutta l\u2019Europa del Sud\u00bb.<\/h5>\n<h5><strong>Se diventer\u00e0 premier nel suo paese, quale sar\u00e0 il primo provvedimento?<\/strong><br \/>\n\u00abRivedere con la Ue non solo il fallimentare memorandum impostoci, ma tutta la politica europea per affrontare la crisi\u00bb.<\/h5>\n<h5><strong>\u00c8 favorevole o no al ritorno della dracma? Un pezzo di Syriza s\u00ec.<\/strong><br \/>\n\u00abL\u2019abbandono della moneta unita non \u00e8 la via d\u2019uscita. Lavoriamo piuttosto a un nuovo patto sociale continentale per l\u2019occupazione e lo sviluppo\u00bb.<\/h5>\n<h5>(<em>la Repubblica<\/em>, 7 febbraio 2014)<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Oggi la Repubblica (p.11) pubblica un&#8217;intervista con Alexis Tsipras raccolta durante il suo tour italiano di questi giorni. Il mio link \u00e8 dal sito di ALBA. ___________________ L\u2019intervista Tsipras e la sfida di sinistra alla Ue \u201cLa linea Merkel porta &hellip; <a href=\"https:\/\/lacittafutura.net\/adrianozanon\/2014\/02\/07\/tsipras-un-greco-come-leader\/\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[172,177,22,109],"class_list":["post-8291","post","type-post","status-publish","format-standard","hentry","category-pol","tag-elezioni-europee","tag-lista-tsipras","tag-sin","tag-ue"],"_links":{"self":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/comments?post=8291"}],"version-history":[{"count":29,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8291\/revisions"}],"predecessor-version":[{"id":8315,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/8291\/revisions\/8315"}],"wp:attachment":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/media?parent=8291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/categories?post=8291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/tags?post=8291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}