{"id":5311,"date":"2013-01-09T18:05:04","date_gmt":"2013-01-09T18:05:04","guid":{"rendered":"http:\/\/lacittafutura.net\/adrianozanon\/?p=5311"},"modified":"2013-01-09T18:49:42","modified_gmt":"2013-01-09T18:49:42","slug":"lega-carega","status":"publish","type":"post","link":"https:\/\/lacittafutura.net\/adrianozanon\/2013\/01\/09\/lega-carega\/","title":{"rendered":"Lega, carega"},"content":{"rendered":"<p><em>Fresco di oggi, settimo di una serie di puntate su &#8220;I poltronifici&#8221;, l&#8217;articolo di Roberto Galullo su Il Sole 24 Ore dedicato alla prassi veneta (diciamo cos\u00ec) merita di essere riprodotto integralmente. I commenti sono superflui (il grassetto \u00e8 mio).<\/em><\/p>\n<p><strong><a href=\"http:\/\/www.ilsole24ore.com\/art\/commenti-e-idee\/2013-01-09\/lotta-spietata-careghe-063719.shtml?uuid=Abve0WIH&amp;fromSearch\">Lotta spietata per le \u00abcareghe\u00bb<\/a><\/strong><br \/>\nIn Veneto anche chi \u00e8 pensionato pu\u00f2 aspirare a essere riassunto<\/p>\n<p><strong>L&#8217;ultimo sigillo del 2012 \u00e8 stato apposto quando i veneti erano distratti dal veglione di Capodanno <\/strong>e i tappi del prosecco di Valdobbiadene erano pronti a saltare coprendo con il loro rumore sordo il crepitio dei fuochi d&#8217;artificio della politica. Il 31 dicembre due consulenze sono state infatti pubblicate sul sito della Regione che gli ha dato anche una numerazione progressiva: n. 187 e n.188. Distratti questa volta dalla Befana, i veneti non si sono forse accorti che il 2013 \u00e8 iniziato come \u00e8 finito il 2012: il 7 gennaio infatti sono arrivate quattro nomine fresche fresche per centinaia di migliaia di euro.<\/p>\n<p>Se volete cercare la prima consulenza o il primo incarico di collaborazione messo in Rete dalla Regione Veneto, dovete tornare indietro nel tempo. Al 2008, allorch\u00e9 gli incarichi furono 444. Nel 2009 la Regione scese a 399, nel 2010 precipit\u00f2 a 291 e nel 2011 si inchiod\u00f2 a quota 186.<\/p>\n<p>In cinque anni \u00e8 stata attribuita a professionisti, universit\u00e0, societ\u00e0 ed enti, una pioggia di incarichi che hanno spaziato dalla consulenza tecnico-scientifica specialistica sulla pianificazione territoriale funzionale (la prima visibile sul sito, il 22 aprile 2008, per un importo di 24.885, 83 euro erogato a un professore universitario) alla gestione sostenibile delle risorse del mare Adriatico (le ultime del 2012 per complessivi 53.030 euro finanziati dalla Ue). In mezzo un mondo di incarichi milionari: 1.512, praticamente al ritmo di uno ogni 29 ore o gi\u00f9 di l\u00ec. A quelle della Giunta si sommano le consulenze del consiglio: 130 dal 2007 a oggi.<\/p>\n<p>Con una ragnatela cos\u00ec estesa di nomine esterne alla Regione, del tutto legittime per carit\u00e0 di Dio, tutto farebbe pensare che le risorse interne siano carenti di agenzie, societ\u00e0 partecipate, enti e istituzioni con uomini e dirigenti in grado di far camminare progetti e idee. Nulla di pi\u00f9 sbagliato. <strong>Se la Regione Veneto concorre al record mondiale di consulenze, \u00e8 molto ben posizionata anche nella speciale classifica internazionale di poltrone nelle Ulss<\/strong> (che sono 22 pi\u00f9 due aziende ospedaliere), commissioni (sette), comitati regionali (due), organismi partecipati (due), osservatori regionali (20 oltre a quello interregionale) ma soprattutto enti (ne ha 20, direttamente o tramite Veneto Sviluppo spa, che spaziano dalla sanit\u00e0 alla polizia locale). L&#8217;Arpav (Agenzia regionale per la prevenzione e protezione ambientale) \u00e8 commissariata: sotto esame la gestione dal 2000 in poi.<\/p>\n<p><strong>Insomma, un caleidoscopio di organismi che entrano direttamente nella vita economica della regione, al centro del quale girano centinaia di poltrone legate spesso alla fedelt\u00e0 politica che dal 1995 ha un sola etichetta (centrodestra tendenza Lega). <\/strong>In 17 enti il Sole-24 Ore ha contato 43 tra presidenti, vicepresidenti e consiglieri con indennit\u00e0 annue lorde che oscillano da 3.300 euro a 152mila euro all&#8217;anno anche se c&#8217;\u00e8 chi non prende nulla per ricoprire l&#8217;incarico a testimonianza che o lo fa per spirito di servizio o lo fa per vantaggi indiretti.<\/p>\n<p>Tra le poltrone calamita la curiosit\u00e0 quella di Luigino Tremonti, cugino del pi\u00f9 noto Giulio. Dall&#8217;11 giugno 2011 \u00e8 amministratore unico delle Terme di Recoaro ma soprattutto amministratore unico, dal 20 maggio dello stesso anno, della Societ\u00e0 veneziana edilizia Canalgrande spa. Il 21 settembre 2011 il consigliere Diego Bottacin (Verso Nord) present\u00f2 in consiglio un&#8217;interrogazione a risposta immediata chiedendo papale papale: \u00abDi cosa si occupa la Societ\u00e0 Veneziana Edilizia Canalgrande Spa? Qual \u00e8 il suo capitale sociale? Quanto costa il suo funzionamento? Come \u00e8 stato scelto Tremonti?\u00bb.<\/p>\n<p>La risposta \u2013 alla faccia dell&#8217;immediatezza &#8211; \u00e8 giunta il 5 marzo 2012 per bocca dell&#8217;assessore al Bilancio Roberto Ciambetti (Lega Nord): il futuro della societ\u00e0 \u00e8 \u00abnell&#8217;avvio di un percorso di accorpamento delle societ\u00e0 a partecipazione regionale operanti nel settore immobiliare, individuando la Societ\u00e0 veneziana edilizia Canalgrande Spa, quale soggetto capofila dell&#8217;operazione\u00bb. Unico cambiamento? A quanto pare s\u00ec, perch\u00e9 la Regione \u00e8 fiera di una societ\u00e0 che detiene il 35% del capitale sociale della societ\u00e0 Ski college spa, costituita nel 1996 \u00abper concorrere alla gestione economica della scuola-convitto per atleti in discipline sportive invernali, aggregata all&#8217;Ipssar di Falcade (Belluno), per conciliare la frequentazione scolastica all&#8217;attivit\u00e0 sportiva agonistica e non, contribuendo alla crescita ed ammodernamento dell&#8217;offerta turistica del territorio\u00bb. Una presenza fondamentale per una societ\u00e0 immobiliare. Quanto a Tremonti, beh, la scelta era obbligata, ha spiegato Ciambetti, visto che \u00ab\u00e8 in possesso di una decennale esperienza nella gestione di immobili maturata come presidente dell&#8217;Ater di Belluno\u00bb.<\/p>\n<p><strong>Il punto \u00e8 che in Veneto sono moltissimi a non capire a cosa serva quel corposo pacchetto di enti, istituzioni e societ\u00e0, quali siano i criteri di nomina (fedelt\u00e0 politica a parte in particolare in quota Galan e Zaia, ex Governatore e Presidente in carica) e a cosa serva tenerle in piedi.<\/strong> Mai come in Veneto, un consiglio regionale \u00e8 bombardato da interrogazioni su questi temi: basta scorrere decine e decine di verbali degli ultimi due anni. E&#8217; facile pescare nel mazzo magari partendo da polemiche recenti. Ad esempio quella del consigliere Antonino Pipitone (Idv) che il 14 febbraio 2012 ha chiesto quanti fossero \u00abi funzionari e dirigenti eccellenti della Regione, delle Ulss e degli enti strumentali regionali andati in pensione e poi riassunti a stretto giro di posta, nello stesso ruolo e con le stesse funzioni o in ruoli e funzioni similari\u00bb. Ancora nessuno gli ha risposto.<\/p>\n<p>Peschiamo ancora nel mazzo. Il 19 maggio 2011 il consigliere Stefano Valdegamberi (Udc) ha presentato un&#8217;interrogazione a risposta immediata chiedendo: \u00abE&#8217;vero che sono stati assunti all&#8217;aeroporto Catullo di Villafranca di Verona familiari diretti ed amici del rappresentante della Regione nel consiglio di amministrazione? Risposta del solito Ciambetti: \u00abTra i soci della societ\u00e0 aeroportuale figura la Veneto Sviluppo spa. la quale possiede lo 0,187% del capitale sociale. Considerata l&#8217;assoluta esiguit\u00e0 della suddetta partecipazione, alla Finanziaria regionale non compete il diritto di nominare alcun componente nel consiglio d&#8217;amministrazione dell&#8217;Aeroporto Valerio Catullo, talch\u00e9 Veneto Sviluppo non ha mai avuto propri rappresentanti in seno agli organi sociali della partecipata. Pertanto, la Regione del Veneto non possiede alcun potere di nomina\/designazione n\u00e9 diretta, n\u00e9 tantomeno indiretta nella suddetta Societ\u00e0\u00bb. Proprio su Veneto Sviluppo, la finanziaria detenuta al 51% dalla Regione che ha chiuso il bilancio 2011 con un disavanzo di 3,5 milioni e che in portafoglio conta una trentina di partecipazioni (comprese quelle di compagnie aeree poi fallite e autodromi in perdita di esercizio, testimoniando forse cos\u00ec inconsciamente l&#8217;amore per il brivido), si sono abbattute negli ultimi anni decine di interrogazione e interpellanze.<\/p>\n<p>La replica di Valdegamberi \u00e8 stata furiosa: \u00abNell&#8217;aeroporto Catullo di Villafranca di Verona, ente a partecipazione pubblica, c&#8217;\u00e8 stato qualche amministratore che ha detto che si ritagliano i posti di assunzione tra i partiti come scambiarsi le figurine: &#8220;tocca a me, tocca a te, questa \u00e8 mia, questa \u00e8 tua&#8221;. Ci sono cose veramente allucinanti dietro l&#8217;utilizzo del denaro pubblico\u00bb. Forse, dietro c&#8217;\u00e8 solo quello che, con un&#8217;altra interrogazione, <strong>il consigliere Pietrangelo Petten\u00f2 (Prc) ha denunciato il 4 luglio 2011 sempre a proposito di Veneto Sviluppo: \u00abAltro che crisi: qui si lotta per le careghe\u00bb. <\/strong>Per chi non mastica il dialetto veneto, ci si scanna per le poltrone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fresco di oggi, settimo di una serie di puntate su &#8220;I poltronifici&#8221;, l&#8217;articolo di Roberto Galullo su Il Sole 24 Ore dedicato alla prassi veneta (diciamo cos\u00ec) merita di essere riprodotto integralmente. I commenti sono superflui (il grassetto \u00e8 mio). &hellip; <a href=\"https:\/\/lacittafutura.net\/adrianozanon\/2013\/01\/09\/lega-carega\/\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[32],"class_list":["post-5311","post","type-post","status-publish","format-standard","hentry","category-pol","tag-lega"],"_links":{"self":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/5311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/comments?post=5311"}],"version-history":[{"count":25,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/5311\/revisions"}],"predecessor-version":[{"id":5336,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/5311\/revisions\/5336"}],"wp:attachment":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/media?parent=5311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/categories?post=5311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/tags?post=5311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}