{"id":10162,"date":"2014-12-17T17:10:35","date_gmt":"2014-12-17T17:10:35","guid":{"rendered":"http:\/\/lacittafutura.net\/adrianozanon\/?p=10162"},"modified":"2014-12-17T17:57:19","modified_gmt":"2014-12-17T17:57:19","slug":"paul-klee-1879-1940","status":"publish","type":"post","link":"https:\/\/lacittafutura.net\/adrianozanon\/2014\/12\/17\/paul-klee-1879-1940\/","title":{"rendered":"Paul Klee (1879-1940)"},"content":{"rendered":"<p><img decoding=\"async\" class=\"ngg-singlepic ngg-none\" src=\"http:\/\/lacittafutura.net\/adrianozanon\/wp-content\/blogs.dir\/5\/files\/ratatuia-2014\/paul-klee-1920-angelus-novus.jpg\" alt=\"paul-klee-1920-angelus-novus\" \/><\/p>\n<p><strong>Centotrentacinque anni fa nasceva <a href=\"http:\/\/it.wikipedia.org\/wiki\/Paul_Klee\">Paul Klee <\/a><\/strong> (M\u00fcnchenbuchsee, 18 dicembre 1879 \u2013 Muralto, 29 giugno 1940), il pittore del Novecento che mi ha pi\u00f9 intrigato. Autore di tanti disegni e dipinti ma anche grande produttore di idee, almeno finch\u00e9 il nazismo lo permise, la sua opera \u00e8 troppo grande ed intensa per essere da me facilmente sintetizzata.\u00a0Cos\u00ec tento\u00a0un approccio ellittico, come direbbe Benedetto Croce.<\/p>\n<p>Riporto qui sopra un suo quadro del 1920, <em>Angelus Novus<\/em>, celebre\u00a0anche perch\u00e9 legato alla vita\u00a0intellettuale di <a href=\"http:\/\/it.wikipedia.org\/wiki\/Walter_Benjamin\">Walter Benjamin<\/a>. Comperato\u00a0a met\u00e0 1921, Benjamin lo tenne quasi sempre con s\u00e9, anche nell&#8217;esilio parigino. Lo diede in consegna a George Bataille solo poco prima del fatale tentativo di fuga verso la Spagna. Ma il quadro l&#8217;aveva ispirato da tempo ed a lui \u00e8 dedicata forse la pi\u00f9 celebre delle sue tesi <em>Sul concetto di storia<\/em>.<\/p>\n<h5 style=\"padding-left: 30px;\">C&#8217;\u00e8 un quadro di Klee che si chiama <em>Angelus Novus<\/em>. Vi \u00e8 rappresentato un angelo che sembra in procinto di allontanarsi da qualcosa su cui ha fisso lo sguardo. I suoi occhi sono spalancati, la bocca \u00e8 aperta, e le ali sono dispiegate. L&#8217;angelo della storia deve avere questo aspetto. Ha il viso rivolto al passato. L\u00e0 dove davanti <em>a noi<\/em> appare una catena di avvenimenti, <em>egli <\/em>vede un&#8217;unica catastrofe, che ammassa incessantemente macerie su macerie e le scaraventa ai suoi piedi. Egli vorrebbe ben trattenersi, destare i morti e riconnettere i frantumi. Ma dal paradiso soffia una bufera, che si \u00e8 impigliata nelle sue ali, ed \u00e8 cos\u00ec forte che l&#8217;angelo non pu\u00f2 pi\u00f9 chiuderle. Questa bufera lo spinge inarrestabilmente nel futuro, a cui egli volge le spalle, mentre cresce verso il cielo il cumulo delle macerie davanti a lui. Ci\u00f2 che noi chiamiamo il progresso, \u00e8 <em>questa<\/em> bufera. (Tesi IX)<\/h5>\n<p>Questo testo trova una particolare sintesi in uno dei testi preparatori:<\/p>\n<h5 style=\"padding-left: 30px;\">Marx dice che le rivoluzioni sono la locomotiva della storia universale. Ma forse le cose stanno in modo del tutto diverso. Forse le rivoluzioni sono il ricorso al freno d&#8217;emergenza da parte del genere umano in viaggio su questo treno. (Ms 1100)<\/h5>\n<p>I profeti &#8211; cio\u00e8 coloro che vedono le cose in anticipo rispetto a tutti &#8211; sono sempre esistiti, non solo nell&#8217;antichit\u00e0, ma esistono tutt&#8217;ora. Benjamin era un profeta che scriveva e Paul Klee uno che disegnava il futuro.<\/p>\n<h5>(I testi sono tratti da: Benjamin W., <em>Sul concetto di storia<\/em> [1940], a cura di Gianfranco Bonola e Michele Ranchetti, Einaudi, Torino 1997.)<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Centotrentacinque anni fa nasceva Paul Klee (M\u00fcnchenbuchsee, 18 dicembre 1879 \u2013 Muralto, 29 giugno 1940), il pittore del Novecento che mi ha pi\u00f9 intrigato. Autore di tanti disegni e dipinti ma anche grande produttore di idee, almeno finch\u00e9 il nazismo &hellip; <a href=\"https:\/\/lacittafutura.net\/adrianozanon\/2014\/12\/17\/paul-klee-1879-1940\/\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148],"tags":[35],"class_list":["post-10162","post","type-post","status-publish","format-standard","hentry","category-arte","tag-mem"],"_links":{"self":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/10162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/comments?post=10162"}],"version-history":[{"count":28,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/10162\/revisions"}],"predecessor-version":[{"id":10188,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/posts\/10162\/revisions\/10188"}],"wp:attachment":[{"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/media?parent=10162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/categories?post=10162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacittafutura.net\/adrianozanon\/wp-json\/wp\/v2\/tags?post=10162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}